{"id":25005,"date":"2024-05-31T14:42:56","date_gmt":"2024-05-31T12:42:56","guid":{"rendered":"https:\/\/btob.poppik.com\/shop\/minizenquetesdinosaures\/"},"modified":"2025-12-01T12:45:03","modified_gmt":"2025-12-01T11:45:03","slug":"minizenquetesdinosaures","status":"publish","type":"product","link":"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/","title":{"rendered":"MINIZENQU\u00caTES\tDINOSAURES"},"content":{"rendered":"<p>L\u2019Agent A.S.T.R.A.U.X. est une super enqu\u00eatrice de l\u2019Acad\u00e9mie des  Enfants Espions. Elle fait \u00e9quipe avec Poilagratou, son doudou qui parle  (et qui zozote dr\u00f4lement !).<br \/> Ensemble et avec l\u2019aide des <strong>miniZenqu\u00eateurs<\/strong>,  ils m\u00e8nent des miniZ<strong>enqu\u00eates myst\u00e9rieuses<\/strong> et rel\u00e8vent tous les d\u00e9fis.<br \/> Chaque <strong>tome<\/strong> contient une histoire rythm\u00e9e par <strong>7 \u00e9nigmes, et est accompagn\u00e9 d&#8217;un objet <\/strong>Top Secret qui permet de r\u00e9soudre l\u2019enqu\u00eate. Ce mat\u00e9riel Top Secret est diff\u00e9rent \u00e0 chaque nouveau tome.<\/p>\n<p>ecommand\u00e9e pour les enfants de <strong>4 \u00e0 6 ans.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Agent A.S.T.R.A.U.X. est une super enqu\u00eatrice de l\u2019Acad\u00e9mie des Enfants Espions. Elle fait \u00e9quipe avec Poilagratou, son doudou qui parle<\/p>\n","protected":false},"featured_media":25292,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[284],"product_tag":[],"class_list":["post-25005","product","type-product","status-publish","has-post-thumbnail","product_cat-96-en-cavale","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MINIZENQU\u00caTES DINOSAURES - Poppik Stickers - Jeux \u00e9ducatifs - Enfants<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MINIZENQU\u00caTES DINOSAURES - Poppik Stickers - Jeux \u00e9ducatifs - Enfants\" \/>\n<meta property=\"og:description\" content=\"L\u2019Agent A.S.T.R.A.U.X. est une super enqu\u00eatrice de l\u2019Acad\u00e9mie des Enfants Espions. Elle fait \u00e9quipe avec Poilagratou, son doudou qui parle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/\" \/>\n<meta property=\"og:site_name\" content=\"Poppik Stickers - Jeux \u00e9ducatifs - Enfants\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T11:45:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/btob.poppik.com\/wp-content\/uploads\/2024\/08\/FrontLaid-trasparent-noshadow_1717164714.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/minizenquetesdinosaures\\\/\",\"url\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/minizenquetesdinosaures\\\/\",\"name\":\"MINIZENQU\u00caTES DINOSAURES - Poppik Stickers - Jeux \u00e9ducatifs - Enfants\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#website\"},\"about\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#organization\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/minizenquetesdinosaures\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/minizenquetesdinosaures\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/btob.poppik.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/FrontLaid-trasparent-noshadow_1717164714.png\",\"datePublished\":\"2024-05-31T12:42:56+00:00\",\"dateModified\":\"2025-12-01T11:45:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/minizenquetesdinosaures\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/minizenquetesdinosaures\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/minizenquetesdinosaures\\\/#primaryimage\",\"url\":\"https:\\\/\\\/btob.poppik.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/FrontLaid-trasparent-noshadow_1717164714.png\",\"contentUrl\":\"https:\\\/\\\/btob.poppik.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/FrontLaid-trasparent-noshadow_1717164714.png\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/minizenquetesdinosaures\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/\",\"name\":\"Poppik Stickers - Jeux \u00e9ducatifs - Enfants\",\"description\":\"Jeux \u00e9ducatifs - Enfants\",\"publisher\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#organization\",\"name\":\"Poppik Stickers - Jeux \u00e9ducatifs - Enfants\",\"url\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/btob.poppik.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo_POPPIK_jaune.png\",\"contentUrl\":\"https:\\\/\\\/btob.poppik.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo_POPPIK_jaune.png\",\"width\":460,\"height\":157,\"caption\":\"Poppik Stickers - Jeux \u00e9ducatifs - Enfants\"},\"image\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MINIZENQU\u00caTES DINOSAURES - Poppik Stickers - Jeux \u00e9ducatifs - Enfants","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/","og_locale":"en_US","og_type":"article","og_title":"MINIZENQU\u00caTES DINOSAURES - Poppik Stickers - Jeux \u00e9ducatifs - Enfants","og_description":"L\u2019Agent A.S.T.R.A.U.X. est une super enqu\u00eatrice de l\u2019Acad\u00e9mie des Enfants Espions. Elle fait \u00e9quipe avec Poilagratou, son doudou qui parle","og_url":"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/","og_site_name":"Poppik Stickers - Jeux \u00e9ducatifs - Enfants","article_modified_time":"2025-12-01T11:45:03+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2024\/08\/FrontLaid-trasparent-noshadow_1717164714.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/","url":"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/","name":"MINIZENQU\u00caTES DINOSAURES - Poppik Stickers - Jeux \u00e9ducatifs - Enfants","isPartOf":{"@id":"https:\/\/btob.poppik.com\/en\/#website"},"about":{"@id":"https:\/\/btob.poppik.com\/en\/#organization"},"primaryImageOfPage":{"@id":"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/#primaryimage"},"image":{"@id":"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/#primaryimage"},"thumbnailUrl":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2024\/08\/FrontLaid-trasparent-noshadow_1717164714.png","datePublished":"2024-05-31T12:42:56+00:00","dateModified":"2025-12-01T11:45:03+00:00","breadcrumb":{"@id":"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/#primaryimage","url":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2024\/08\/FrontLaid-trasparent-noshadow_1717164714.png","contentUrl":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2024\/08\/FrontLaid-trasparent-noshadow_1717164714.png","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/btob.poppik.com\/en\/shop\/minizenquetesdinosaures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/btob.poppik.com\/en\/#website","url":"https:\/\/btob.poppik.com\/en\/","name":"Poppik Stickers - Jeux \u00e9ducatifs - Enfants","description":"Jeux \u00e9ducatifs - Enfants","publisher":{"@id":"https:\/\/btob.poppik.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/btob.poppik.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/btob.poppik.com\/en\/#organization","name":"Poppik Stickers - Jeux \u00e9ducatifs - Enfants","url":"https:\/\/btob.poppik.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/btob.poppik.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2021\/09\/Logo_POPPIK_jaune.png","contentUrl":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2021\/09\/Logo_POPPIK_jaune.png","width":460,"height":157,"caption":"Poppik Stickers - Jeux \u00e9ducatifs - Enfants"},"image":{"@id":"https:\/\/btob.poppik.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/product\/25005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/media\/25292"}],"wp:attachment":[{"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/media?parent=25005"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/product_brand?post=25005"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/product_cat?post=25005"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/product_tag?post=25005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}