{"id":24431,"date":"2024-01-08T09:58:17","date_gmt":"2024-01-08T08:58:17","guid":{"rendered":"https:\/\/btob.poppik.com\/shop\/chevalet-ce2-cm1-cm2\/"},"modified":"2024-01-08T10:13:20","modified_gmt":"2024-01-08T09:13:20","slug":"chevalet-ce2-cm1-cm2","status":"publish","type":"product","link":"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/","title":{"rendered":"CHEVALET CE2 CM1 CM2"},"content":{"rendered":"<p>D\u00e9couvrez le <strong>chevalet CE2, CM1 et CM2<\/strong> de l&#8217;<strong>\u00c9toilium<\/strong> le r\u00e9servoir d&#8217;\u00e9toiles, un ensemble de <strong>fiches d\u2019exercices<\/strong> joliment illustr\u00e9es pour jouer avec l&#8217;\u00c9toilium, un ordinateur m\u00e9canique p\u00e9dagogique innovant. <strong>1 000 questions<\/strong> permettant de travailler les fondamentaux de <strong>Fran\u00e7ais<\/strong> et de <strong>Math\u00e9matiques<\/strong> pour les les enfants de 8 \u00e0 11 ans.<br \/>Combin\u00e9es avec l\u2019\u00c9toilium, ces fiches permettent \u00e0 tous les enfants de s\u2019entra\u00eener, d&#8217;apprendre et  d&#8217;\u00e9valuer leurs comp\u00e9tences en toute autonomie sur les notions  essentielles du programme de l\u2019\u00c9ducation Nationale. Elles sont con\u00e7ues  par des enseignants dipl\u00f4m\u00e9s et conforment aux programmes de l\u2019Education  Nationale. Des le\u00e7ons claires et synth\u00e9tiques permettent aux enfants de  trouver facilement les informations n\u00e9cessaires \u00e0 la r\u00e9alisation de  leurs exercices.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le chevalet CE2, CM1 et CM2 de l&#8217;\u00c9toilium le r\u00e9servoir d&#8217;\u00e9toiles, un ensemble de fiches d\u2019exercices joliment illustr\u00e9es pour<\/p>\n","protected":false},"featured_media":24434,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[288],"product_tag":[],"class_list":["post-24431","product","type-product","status-publish","has-post-thumbnail","product_cat-99-etoilium","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CHEVALET CE2 CM1 CM2 - Poppik Stickers - Jeux \u00e9ducatifs - Enfants<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHEVALET CE2 CM1 CM2 - Poppik Stickers - Jeux \u00e9ducatifs - Enfants\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez le chevalet CE2, CM1 et CM2 de l&#8217;\u00c9toilium le r\u00e9servoir d&#8217;\u00e9toiles, un ensemble de fiches d\u2019exercices joliment illustr\u00e9es pour\" \/>\n<meta property=\"og:url\" content=\"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/\" \/>\n<meta property=\"og:site_name\" content=\"Poppik Stickers - Jeux \u00e9ducatifs - Enfants\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-08T09:13:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/btob.poppik.com\/wp-content\/uploads\/2024\/01\/Chevaletcycle2_1703860392.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/chevalet-ce2-cm1-cm2\\\/\",\"url\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/chevalet-ce2-cm1-cm2\\\/\",\"name\":\"CHEVALET CE2 CM1 CM2 - Poppik Stickers - Jeux \u00e9ducatifs - Enfants\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#website\"},\"about\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#organization\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/chevalet-ce2-cm1-cm2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/chevalet-ce2-cm1-cm2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/btob.poppik.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Chevaletcycle2_1703860392.jpg\",\"datePublished\":\"2024-01-08T08:58:17+00:00\",\"dateModified\":\"2024-01-08T09:13:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/chevalet-ce2-cm1-cm2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/chevalet-ce2-cm1-cm2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/chevalet-ce2-cm1-cm2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/btob.poppik.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Chevaletcycle2_1703860392.jpg\",\"contentUrl\":\"https:\\\/\\\/btob.poppik.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Chevaletcycle2_1703860392.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/shop\\\/chevalet-ce2-cm1-cm2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/\",\"name\":\"Poppik Stickers - Jeux \u00e9ducatifs - Enfants\",\"description\":\"Jeux \u00e9ducatifs - Enfants\",\"publisher\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#organization\",\"name\":\"Poppik Stickers - Jeux \u00e9ducatifs - Enfants\",\"url\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/btob.poppik.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo_POPPIK_jaune.png\",\"contentUrl\":\"https:\\\/\\\/btob.poppik.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo_POPPIK_jaune.png\",\"width\":460,\"height\":157,\"caption\":\"Poppik Stickers - Jeux \u00e9ducatifs - Enfants\"},\"image\":{\"@id\":\"https:\\\/\\\/btob.poppik.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHEVALET CE2 CM1 CM2 - Poppik Stickers - Jeux \u00e9ducatifs - Enfants","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/","og_locale":"en_US","og_type":"article","og_title":"CHEVALET CE2 CM1 CM2 - Poppik Stickers - Jeux \u00e9ducatifs - Enfants","og_description":"D\u00e9couvrez le chevalet CE2, CM1 et CM2 de l&#8217;\u00c9toilium le r\u00e9servoir d&#8217;\u00e9toiles, un ensemble de fiches d\u2019exercices joliment illustr\u00e9es pour","og_url":"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/","og_site_name":"Poppik Stickers - Jeux \u00e9ducatifs - Enfants","article_modified_time":"2024-01-08T09:13:20+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2024\/01\/Chevaletcycle2_1703860392.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/","url":"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/","name":"CHEVALET CE2 CM1 CM2 - Poppik Stickers - Jeux \u00e9ducatifs - Enfants","isPartOf":{"@id":"https:\/\/btob.poppik.com\/en\/#website"},"about":{"@id":"https:\/\/btob.poppik.com\/en\/#organization"},"primaryImageOfPage":{"@id":"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/#primaryimage"},"image":{"@id":"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/#primaryimage"},"thumbnailUrl":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2024\/01\/Chevaletcycle2_1703860392.jpg","datePublished":"2024-01-08T08:58:17+00:00","dateModified":"2024-01-08T09:13:20+00:00","breadcrumb":{"@id":"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/#primaryimage","url":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2024\/01\/Chevaletcycle2_1703860392.jpg","contentUrl":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2024\/01\/Chevaletcycle2_1703860392.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/btob.poppik.com\/en\/shop\/chevalet-ce2-cm1-cm2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/btob.poppik.com\/en\/#website","url":"https:\/\/btob.poppik.com\/en\/","name":"Poppik Stickers - Jeux \u00e9ducatifs - Enfants","description":"Jeux \u00e9ducatifs - Enfants","publisher":{"@id":"https:\/\/btob.poppik.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/btob.poppik.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/btob.poppik.com\/en\/#organization","name":"Poppik Stickers - Jeux \u00e9ducatifs - Enfants","url":"https:\/\/btob.poppik.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/btob.poppik.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2021\/09\/Logo_POPPIK_jaune.png","contentUrl":"https:\/\/btob.poppik.com\/wp-content\/uploads\/2021\/09\/Logo_POPPIK_jaune.png","width":460,"height":157,"caption":"Poppik Stickers - Jeux \u00e9ducatifs - Enfants"},"image":{"@id":"https:\/\/btob.poppik.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/product\/24431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/media\/24434"}],"wp:attachment":[{"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/media?parent=24431"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/product_brand?post=24431"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/product_cat?post=24431"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/btob.poppik.com\/en\/wp-json\/wp\/v2\/product_tag?post=24431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}